{"id":29072,"date":"2025-05-15T17:46:10","date_gmt":"2025-05-15T16:46:10","guid":{"rendered":"https:\/\/www.caiadoguerreiro.com\/?p=29072"},"modified":"2025-05-15T17:46:10","modified_gmt":"2025-05-15T16:46:10","slug":"conflicts-between-partners-risks-solutions-and-the-importance-of-specialized-legal-support","status":"publish","type":"post","link":"https:\/\/www.caiadoguerreiro.com\/en\/conflicts-between-partners-risks-solutions-and-the-importance-of-specialized-legal-support\/","title":{"rendered":"Conflicts Between Partners: Risks, Solutions, and the Importance of Specialized Legal Support"},"content":{"rendered":"<p>As disputas entre s\u00f3cios s\u00e3o, desde sempre, uma das principais fontes de instabilidade nas empresas, independentemente da sua dimens\u00e3o, setor ou antiguidade.<\/p>\n<p>A perda de confian\u00e7a entre s\u00f3cios, aliada a comportamentos considerados desleais, pode comprometer seriamente a atividade da sociedade e prejudicar os seus trabalhadores e credores.<\/p>\n<p>\u00c9 frequente que os conflitos surjam por atos como a discord\u00e2ncia na gest\u00e3o, a apropria\u00e7\u00e3o indevida de bens da empresa, o aproveitamento pessoal de oportunidades de neg\u00f3cio, a concorr\u00eancia desleal ou a divulga\u00e7\u00e3o de informa\u00e7\u00f5es confidenciais. Por vezes, existem simples suspeitas; noutras situa\u00e7\u00f5es, os comportamentos s\u00e3o evidentes e documentados.<\/p>\n<p>Nestes casos, existem mecanismos legais que podem ser acionados. Desde logo, a exclus\u00e3o do s\u00f3cio apresenta-se como uma das solu\u00e7\u00f5es mais eficazes, embora a sua prova seja exigente. Esta medida requer, pois, prova clara de que a conduta do s\u00f3cio torna insustent\u00e1vel a sua perman\u00eancia, provocando preju\u00edzos s\u00e9rios \u00e0 sociedade. Importa, no entanto, salientar que esta solu\u00e7\u00e3o est\u00e1 legalmente prevista apenas para sociedades por quotas, sendo a sua aplica\u00e7\u00e3o a sociedades an\u00f3nimas juridicamente controversa.<\/p>\n<p>Outra hip\u00f3tese \u00e9 a amortiza\u00e7\u00e3o da participa\u00e7\u00e3o social, poss\u00edvel quando prevista nos estatutos. Esta solu\u00e7\u00e3o permite retirar o s\u00f3cio da estrutura societ\u00e1ria sem a sua concord\u00e2ncia, desde que se comprove a exist\u00eancia de uma conduta lesiva com impacto relevante.<\/p>\n<p>Podem ainda ser equacionadas alternativas que exigem algum n\u00edvel de coopera\u00e7\u00e3o, como a compra da participa\u00e7\u00e3o do s\u00f3cio desleal, muitas vezes prevista em acordos parassociais, ou o aumento de capital, que pode diluir a posi\u00e7\u00e3o do s\u00f3cio desde que este n\u00e3o acompanhe o investimento.<\/p>\n<p>Tamb\u00e9m \u00e9 poss\u00edvel considerar a exonera\u00e7\u00e3o do s\u00f3cio lesado, nos casos em que este pretenda abandonar a sociedade por n\u00e3o existir uma solu\u00e7\u00e3o vi\u00e1vel para afastar o s\u00f3cio desleal. Contudo, trata-se de um caminho legalmente mais restrito.<\/p>\n<p>Para al\u00e9m disso, e sempre que haja risco iminente de preju\u00edzo, \u00e9 poss\u00edvel requerer ao tribunal uma provid\u00eancia cautelar que suspenda os comportamentos lesivos, ou avan\u00e7ar com uma a\u00e7\u00e3o de responsabilidade civil para exigir indemniza\u00e7\u00e3o pelos danos causados.<\/p>\n<p>No fundo, e dada a complexidade destas situa\u00e7\u00f5es e o rigor dos tribunais na aplica\u00e7\u00e3o dos crit\u00e9rios legais, \u00e9 fundamental obter aconselhamento junto de um advogado com experi\u00eancia em contencioso societ\u00e1rio, garantindo uma abordagem segura e adaptada \u00e0 realidade da empresa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As disputas entre s\u00f3cios s\u00e3o, desde sempre, uma das principais fontes de instabilidade nas empresas, independentemente da sua dimens\u00e3o, setor ou antiguidade. A perda de confian\u00e7a entre s\u00f3cios, aliada a comportamentos considerados desleais, pode comprometer seriamente a atividade da sociedade e prejudicar os seus trabalhadores e credores. \u00c9 frequente que os conflitos surjam por atos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29073,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","areas-arbitration","areas-litigation"],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.caiadoguerreiro.com\/wp-content\/uploads\/2025\/05\/CFSFD1-EN-1.png","_links":{"self":[{"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/posts\/29072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/comments?post=29072"}],"version-history":[{"count":3,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/posts\/29072\/revisions"}],"predecessor-version":[{"id":29079,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/posts\/29072\/revisions\/29079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/media\/29073"}],"wp:attachment":[{"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/media?parent=29072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/categories?post=29072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caiadoguerreiro.com\/en\/wp-json\/wp\/v2\/tags?post=29072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}